{"id":4677,"date":"2024-02-02T08:31:46","date_gmt":"2024-02-02T08:31:46","guid":{"rendered":"https:\/\/reinmedical.com\/conclusione-di-medica-2023\/"},"modified":"2024-08-30T15:37:52","modified_gmt":"2024-08-30T15:37:52","slug":"conclusione-di-medica-2023","status":"publish","type":"post","link":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/","title":{"rendered":"Conclusione di MEDICA 2023"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background fusion-parallax-none nonhundred-percent-fullwidth non-hundred-percent-height-scrolling lazyload gradient-container-1\" style=\"--awb-background-position:center bottom;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-min-height:250px;--awb-background-size:cover;--awb-flex-wrap:wrap;\" data-bg=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/HeaderrMedica3_0.png\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gradient-container-2\" style=\"--awb-background-position:center bottom;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-min-height:543px;--awb-background-color:var(--awb-color3);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_4_5 4_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:80%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.4%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.4%;--awb-width-medium:80%;--awb-order-medium:0;--awb-spacing-right-medium:2.4%;--awb-spacing-left-medium:2.4%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h1>Conclusione di MEDICA 2023<\/h1>\n<h2>Rein Medical presenta una selezione del suo portfolio a MEDICA<\/h2>\n<p>  Anche quest&#8217;anno <strong>MEDICA<\/strong> a D\u00fcsseldorf ha consolidato la sua posizione di fiera medica pi\u00f9 grande del mondo.<br \/>\nPi\u00f9 di 5.300 espositori sono stati lieti di accogliere circa 83.000 visitatori provenienti da 166 paesi.<br \/>\n&#8220;Abbiamo sfruttato la fiera anche per dialogare, soprattutto con partner e clienti internazionali. Oltre a discussioni interessanti, abbiamo portato via una o due idee per ulteriori innovazioni&#8221;, afferma Stephan Rein, Amministratore Delegato di Rein Medical, riassumendo positivamente MEDICA 2023.<br \/>\n&#8220;Inoltre, il nostro nuovo Direttore Generale dal Medio Oriente ha visitato questo evento per la prima volta per nostro conto&#8221;.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_5 1_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:20%;--awb-margin-top-large:0px;--awb-spacing-right-large:9.6%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:9.6%;--awb-width-medium:20%;--awb-order-medium:0;--awb-spacing-right-medium:9.6%;--awb-spacing-left-medium:9.6%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gradient-container-3\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><div id=\"paragraph_422\" class=\"paragraph paragraph_text_link text-normal\">\n<div class=\"col-12 col-lg-9 offset-lg-2 col-xl-8 offset-xl-2 slide-in from-bottom image_text_wrapper visible\">\n<h2><strong><span lang=\"DE\">Flusso di lavoro <\/span><\/strong><strong><span lang=\"DE\">sotto controllo in sala operatoria<\/span><\/strong><\/h2>\n<p><span lang=\"DE\" xml:lang=\"DE\">In qualit\u00e0 di co-espositore con <strong>Dr. Mach GmbH &amp; Co. KG <\/strong>, Rein Medical si \u00e8 concentrato su un&#8217;ampia gamma di soluzioni per ottimizzare i flussi di lavoro in sala operatoria. &#8220;Con i monitor e i PC all-in-one delle serie OPERION e CLINIO e il software SMART OR, offriamo soluzioni personalizzate per ogni esigenza e supportiamo i clienti dalla pianificazione alla consegna. Siamo stati molto contenti dei numerosi colloqui personali che abbiamo avuto al nostro stand a D\u00fcsseldorf&#8221;, afferma Rein.<br \/>\n&#8220;Purtroppo <\/span>  I grandi attori del settore medico erano assenti come calamite e quindi i nostri clienti tedeschi erano poco rappresentati&#8221;.  <\/p>\n<h2><strong><span lang=\"DE\" xml:lang=\"DE\">Tutto in vista  <\/span><\/strong><\/h2>\n<p><span lang=\"DE\">Da molti anni OPERION \u00e8 sinonimo di<\/span><span lang=\"DE\"> monitor integrati a parete <\/span><span lang=\"DE\">e postazioni di lavoro per <\/span><span lang=\"DE\">il<\/span><span lang=\"DE\" xml:lang=\"DE\">  Sala operatoria &#8211; igienica, altamente compatibile, affidabile e intuitiva da usare.<br \/>\nCon dimensioni diverse, da 21,5 a 65 pollici.   <\/span><span lang=\"DE\" xml:lang=\"DE\">trasformano ogni sala operatoria in un centro di prestazioni digitali.<br \/>\nI monitor sono presenti in oltre 6.500 sale operatorie in tutto il mondo, il 60% delle quali \u00e8 dotato di unit\u00e0 PC integrate.   <\/span><\/p>\n<p><span lang=\"DE\" xml:lang=\"DE\">I monitor a parete e le postazioni di lavoro OPERION si adattano perfettamente a qualsiasi sala operatoria: sia nelle nuove costruzioni che nella ristrutturazione di una sala operatoria esistente.  <\/span><span lang=\"DE\" xml:lang=\"DE\">Nelle sale operatorie con un sistema modulare a parete, OPERION pu\u00f2 essere installato ad incasso e quindi integrato in modo completo e igienico come parte del sistema a parete.<br \/>\nQuesto design rappresenta l&#8217;integrazione pi\u00f9 igienica ed economica del monitor.<br \/>\nSe \u00e8 possibile montarlo solo in superficie, gli alloggiamenti in alluminio massiccio di alta qualit\u00e0 garantiscono un&#8217;installazione sicura.<br \/>\nPoich\u00e9 i telai e gli alloggiamenti montati in superficie sono rivestiti con una speciale vernice a polvere germicida, possono essere puliti in modo semplice e igienico.   <\/span><\/p>\n<p><span lang=\"DE\" xml:lang=\"DE\">I sistemi OPERION sono certificati come dispositivi medici di Classe I e offrono una sicurezza appropriata per l&#8217;uso nell&#8217;ambiente del paziente.<\/span><\/p>\n<h2><strong><span lang=\"DE\" xml:lang=\"DE\">La brillantezza \u00e8 la carta vincente<\/span><\/strong><\/h2>\n<p><span lang=\"DE\">Il monitor CLINIO \u00e8 anche un dispositivo medico di Classe I <\/span><span lang=\"DE\">secondo la normativa MDR<\/span><span lang=\"DE\"> e convince per la sua grande flessibilit\u00e0 in termini di formati di input e per le speciali propriet\u00e0 di colore e immagine. <\/span> <\/p>\n<p><span lang=\"DE\" xml:lang=\"DE\">CLINIO \u00e8 il monitor chirurgico perfetto.<br \/>\n\u00c8 caratterizzato da un basso consumo energetico e da un design compatto.<br \/>\nLa qualit\u00e0 brillante delle immagini e la riproduzione ottimale dei colori sono garantite da una calibrazione 3D LUT di fabbrica per DICOM, BT.709, BT.1886 e BT.2020.<br \/>\n\u00c8 disponibile in formato UHD da 27 e 32 pollici.   <\/span><\/p>\n<p><span lang=\"DE\" xml:lang=\"DE\">Il robusto alloggiamento \u00e8 realizzato interamente in alluminio.<br \/>\nLo sportello igienico e le varie guarnizioni dei cavi impediscono a polvere, sporco e liquidi di penetrare.<br \/>\nL&#8217;alloggiamento, con protezione IP54, \u00e8 rivestito con una vernice a polvere germicida, \u00e8 chiuso su tutti i lati e pu\u00f2 essere disinfettato igienicamente.    <\/span><\/p>\n<h2><strong><span lang=\"DE\" xml:lang=\"DE\">Controllo dell&#8217;intero flusso di informazioni in sala operatoria<\/span><\/strong><\/h2>\n<p><span lang=\"DE\" xml:lang=\"DE\">Se le immagini e i video devono essere distribuiti, registrati e gestiti in sala operatoria e non solo, SMART OR \u00e8 la soluzione giusta: dalla singola postazione di lavoro, quando si devono documentare immagini e dati audio provenienti da fonti locali, fino alla distribuzione di immagini, all&#8217;archiviazione e allo streaming in reti complesse.<\/span><\/p>\n<p><span lang=\"DE\" xml:lang=\"DE\">In aggiunta al  <\/span><span lang=\"DE\" xml:lang=\"DE\">Il routing, la distribuzione del segnale all&#8217;interno della stanza, codifica e consente lo streaming veloce e ottimizzato della larghezza di banda dei contenuti multimediali all&#8217;interno della rete IT.<br \/>\nA ci\u00f2 si aggiunge una gestione completa del segnale e la sua disponibilit\u00e0 a livello di rete.<br \/>\nSMART OR permette anche di documentare comodamente le singole immagini e le sequenze video e audio relative al paziente e alla procedura.<br \/>\nI dispositivi e i sistemi informativi sono collegati tramite standard consolidati come HL7 e DICOM.<br \/>\nIl controllo mirato dei componenti dell&#8217;ambiente e dei flussi di lavoro consente lo streaming e l&#8217;editing di video e immagini in tutto l&#8217;ospedale e l&#8217;assegnazione diretta ai pazienti.    <\/span><\/p>\n<p><span lang=\"DE\" xml:lang=\"DE\">Insieme al suo partner Dr Mach, Rein Medical ha presentato l&#8217;integrazione di una lampada chirurgica con telecamera 4K integrata nel sistema di gestione dei segnali SMART OR.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gradient-container-4\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_5 1_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:20%;--awb-margin-top-large:0px;--awb-spacing-right-large:9.6%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:9.6%;--awb-width-medium:20%;--awb-order-medium:0;--awb-spacing-right-medium:9.6%;--awb-spacing-left-medium:9.6%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_3_5 3_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:60%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.2%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.2%;--awb-width-medium:60%;--awb-order-medium:0;--awb-spacing-right-medium:3.2%;--awb-spacing-left-medium:3.2%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-carousel fusion-image-carousel-auto fusion-image-carousel-1\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel awb-carousel--carousel awb-swiper-dots-position-bottom\" data-layout=\"carousel\" data-autoplay=\"no\" data-autoplayspeed=\"2500\" data-autoplaypause=\"no\" data-columns=\"1\" data-columnsmedium=\"1\" data-columnssmall=\"1\" data-itemmargin=\"1\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-freemode=\"no\" data-imagesize=\"auto\" data-scrollitems=\"0\" data-centeredslides=\"no\" data-rotationangle=\"50\" data-depth=\"100\" data-speed=\"500\" data-shadow=\"no\" data-pagination=\"bullets\" style=\"--awb-columns:1;--awb-column-spacing:1px;\"><div class=\"swiper-wrapper awb-image-carousel-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"1600\" height=\"1596\" src=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1.jpeg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271600%27%20height%3D%271596%27%20viewBox%3D%270%200%201600%201596%27%3E%3Crect%20width%3D%271600%27%20height%3D%271596%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1.jpeg\" data-srcset=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-66x66.jpeg 66w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-150x150.jpeg 150w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-200x200.jpeg 200w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-300x300.jpeg 300w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-400x399.jpeg 400w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-500x499.jpeg 500w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-600x599.jpeg 600w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-700x698.jpeg 700w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-768x766.jpeg 768w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-800x798.jpeg 800w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-1024x1021.jpeg 1024w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-1200x1197.jpeg 1200w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1-1536x1532.jpeg 1536w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA1_1.jpeg 1600w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1.jpeg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271600%27%20height%3D%271200%27%20viewBox%3D%270%200%201600%201200%27%3E%3Crect%20width%3D%271600%27%20height%3D%271200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1.jpeg\" data-srcset=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1-200x150.jpeg 200w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1-300x225.jpeg 300w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1-400x300.jpeg 400w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1-500x375.jpeg 500w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1-600x450.jpeg 600w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1-700x525.jpeg 700w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1-768x576.jpeg 768w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1-800x600.jpeg 800w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1-1024x768.jpeg 1024w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1-1200x900.jpeg 1200w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1-1536x1152.jpeg 1536w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/Medica2_1.jpeg 1600w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"1200\" height=\"1600\" src=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA3_1.jpeg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%271600%27%20viewBox%3D%270%200%201200%201600%27%3E%3Crect%20width%3D%271200%27%20height%3D%271600%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA3_1.jpeg\" data-srcset=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA3_1-200x267.jpeg 200w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA3_1-225x300.jpeg 225w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA3_1-400x533.jpeg 400w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA3_1-500x667.jpeg 500w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA3_1-600x800.jpeg 600w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA3_1-700x933.jpeg 700w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA3_1-768x1024.jpeg 768w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA3_1-800x1067.jpeg 800w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA3_1-1152x1536.jpeg 1152w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA3_1.jpeg 1200w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"1200\" height=\"1600\" src=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA4_1.jpeg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%271600%27%20viewBox%3D%270%200%201200%201600%27%3E%3Crect%20width%3D%271200%27%20height%3D%271600%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA4_1.jpeg\" data-srcset=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA4_1-200x267.jpeg 200w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA4_1-225x300.jpeg 225w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA4_1-400x533.jpeg 400w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA4_1-500x667.jpeg 500w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA4_1-600x800.jpeg 600w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA4_1-700x933.jpeg 700w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA4_1-768x1024.jpeg 768w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA4_1-800x1067.jpeg 800w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA4_1-1152x1536.jpeg 1152w, https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA4_1.jpeg 1200w\" data-sizes=\"auto\" \/><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_5 1_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:20%;--awb-margin-top-large:0px;--awb-spacing-right-large:9.6%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:9.6%;--awb-width-medium:20%;--awb-order-medium:0;--awb-spacing-right-medium:9.6%;--awb-spacing-left-medium:9.6%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2433,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[163],"tags":[],"class_list":["post-4677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evento-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conclusione di MEDICA 2023 - Rein Medical<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conclusione di MEDICA 2023 - Rein Medical\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Rein Medical\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-02T08:31:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-30T15:37:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA_0.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"34 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/conclusione-di-medica-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/conclusione-di-medica-2023\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/#\\\/schema\\\/person\\\/b1378b4bd1058be4cf876e1916a30174\"},\"headline\":\"Conclusione di MEDICA 2023\",\"datePublished\":\"2024-02-02T08:31:46+00:00\",\"dateModified\":\"2024-08-30T15:37:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/conclusione-di-medica-2023\\\/\"},\"wordCount\":6847,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/conclusione-di-medica-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reinmedical.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/MEDICA_0.png\",\"articleSection\":[\"Evento\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/conclusione-di-medica-2023\\\/\",\"url\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/conclusione-di-medica-2023\\\/\",\"name\":\"Conclusione di MEDICA 2023 - Rein Medical\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/conclusione-di-medica-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/conclusione-di-medica-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reinmedical.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/MEDICA_0.png\",\"datePublished\":\"2024-02-02T08:31:46+00:00\",\"dateModified\":\"2024-08-30T15:37:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/#\\\/schema\\\/person\\\/b1378b4bd1058be4cf876e1916a30174\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/conclusione-di-medica-2023\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/reinmedical.com\\\/it\\\/conclusione-di-medica-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/conclusione-di-medica-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/reinmedical.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/MEDICA_0.png\",\"contentUrl\":\"https:\\\/\\\/reinmedical.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/MEDICA_0.png\",\"width\":650,\"height\":648},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/conclusione-di-medica-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conclusione di MEDICA 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/\",\"name\":\"Rein Medical\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/#\\\/schema\\\/person\\\/b1378b4bd1058be4cf876e1916a30174\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cea383344ba28565fe30ef941da2988d577fe8827a60cf8b7ad5c1ded27b701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cea383344ba28565fe30ef941da2988d577fe8827a60cf8b7ad5c1ded27b701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cea383344ba28565fe30ef941da2988d577fe8827a60cf8b7ad5c1ded27b701?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/wp.hannas-makramee.de\"],\"url\":\"https:\\\/\\\/reinmedical.com\\\/it\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conclusione di MEDICA 2023 - Rein Medical","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/","og_locale":"it_IT","og_type":"article","og_title":"Conclusione di MEDICA 2023 - Rein Medical","og_url":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/","og_site_name":"Rein Medical","article_published_time":"2024-02-02T08:31:46+00:00","article_modified_time":"2024-08-30T15:37:52+00:00","og_image":[{"width":650,"height":648,"url":"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA_0.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"34 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/#article","isPartOf":{"@id":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/"},"author":{"name":"admin","@id":"https:\/\/reinmedical.com\/it\/#\/schema\/person\/b1378b4bd1058be4cf876e1916a30174"},"headline":"Conclusione di MEDICA 2023","datePublished":"2024-02-02T08:31:46+00:00","dateModified":"2024-08-30T15:37:52+00:00","mainEntityOfPage":{"@id":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/"},"wordCount":6847,"commentCount":0,"image":{"@id":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA_0.png","articleSection":["Evento"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/","url":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/","name":"Conclusione di MEDICA 2023 - Rein Medical","isPartOf":{"@id":"https:\/\/reinmedical.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/#primaryimage"},"image":{"@id":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA_0.png","datePublished":"2024-02-02T08:31:46+00:00","dateModified":"2024-08-30T15:37:52+00:00","author":{"@id":"https:\/\/reinmedical.com\/it\/#\/schema\/person\/b1378b4bd1058be4cf876e1916a30174"},"breadcrumb":{"@id":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/#primaryimage","url":"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA_0.png","contentUrl":"https:\/\/reinmedical.com\/wp-content\/uploads\/2024\/02\/MEDICA_0.png","width":650,"height":648},{"@type":"BreadcrumbList","@id":"https:\/\/reinmedical.com\/it\/conclusione-di-medica-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/reinmedical.com\/it\/casa\/"},{"@type":"ListItem","position":2,"name":"Conclusione di MEDICA 2023"}]},{"@type":"WebSite","@id":"https:\/\/reinmedical.com\/it\/#website","url":"https:\/\/reinmedical.com\/it\/","name":"Rein Medical","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reinmedical.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/reinmedical.com\/it\/#\/schema\/person\/b1378b4bd1058be4cf876e1916a30174","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5cea383344ba28565fe30ef941da2988d577fe8827a60cf8b7ad5c1ded27b701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5cea383344ba28565fe30ef941da2988d577fe8827a60cf8b7ad5c1ded27b701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5cea383344ba28565fe30ef941da2988d577fe8827a60cf8b7ad5c1ded27b701?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/wp.hannas-makramee.de"],"url":"https:\/\/reinmedical.com\/it\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/reinmedical.com\/it\/wp-json\/wp\/v2\/posts\/4677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reinmedical.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reinmedical.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reinmedical.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reinmedical.com\/it\/wp-json\/wp\/v2\/comments?post=4677"}],"version-history":[{"count":0,"href":"https:\/\/reinmedical.com\/it\/wp-json\/wp\/v2\/posts\/4677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reinmedical.com\/it\/wp-json\/wp\/v2\/media\/2433"}],"wp:attachment":[{"href":"https:\/\/reinmedical.com\/it\/wp-json\/wp\/v2\/media?parent=4677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reinmedical.com\/it\/wp-json\/wp\/v2\/categories?post=4677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reinmedical.com\/it\/wp-json\/wp\/v2\/tags?post=4677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}